{"id":24128,"date":"2025-01-16T16:14:12","date_gmt":"2025-01-16T20:14:12","guid":{"rendered":"https:\/\/www.asofinbolivia.com\/?p=24128"},"modified":"2025-01-16T16:28:31","modified_gmt":"2025-01-16T20:28:31","slug":"ecofuturo-experimento-un-crecimiento-en-los-servicios-digitales-enfocados-en-la-seguridad-del-usuario","status":"publish","type":"post","link":"https:\/\/asofinbolivia.com\/index.php\/2025\/01\/16\/ecofuturo-experimento-un-crecimiento-en-los-servicios-digitales-enfocados-en-la-seguridad-del-usuario\/","title":{"rendered":"ECOFUTURO EXPERIMENT\u00d3 UN CRECIMIENTO EN LOS SERVICIOS DIGITALES ENFOCADOS EN LA SEGURIDAD DEL USUARIO"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"24128\" class=\"elementor elementor-24128\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32e9019 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32e9019\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-01ea6eb\" data-id=\"01ea6eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6268cd elementor-widget elementor-widget-shortcode\" data-id=\"d6268cd\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"6235\" class=\"elementor elementor-6235\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cd8937b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd8937b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40cee71\" data-id=\"40cee71\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75e4b08 elementor-widget elementor-widget-button\" data-id=\"75e4b08\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-skew-backward\" href=\"https:\/\/asofinbolivia.com\/index.php\/publicaciones\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-left\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver Atr\u00e1s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b274e85\" data-id=\"b274e85\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0a611e8\" data-id=\"0a611e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cb1105 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5cb1105\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b3bbc2a\" data-id=\"b3bbc2a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-729eb20\" data-id=\"729eb20\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8efd166 elementor-widget elementor-widget-heading\" data-id=\"8efd166\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ECOFUTURO EXPERIMENT\u00d3 UN CRECIMIENTO EN LOS SERVICIOS DIGITALES ENFOCADOS EN LA SEGURIDAD DEL USUARIO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-995e5fc elementor-widget elementor-widget-text-editor\" data-id=\"995e5fc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">A septiembre de 2024, las transacciones digitales en Banco Ecofuturo crecieron un 100%, alcanzando 230.454 operaciones electr\u00f3nicas. La entidad refuerza su compromiso con la seguridad digital mediante tecnolog\u00eda avanzada y educaci\u00f3n financiera para proteger a sus clientes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-338bbfd elementor-widget elementor-widget-image\" data-id=\"338bbfd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/asofinbolivia.com\/wp-content\/uploads\/2025\/01\/2024121812012536676-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-24129\" alt=\"\" srcset=\"https:\/\/asofinbolivia.com\/wp-content\/uploads\/2025\/01\/2024121812012536676-768x512.jpg 768w, https:\/\/asofinbolivia.com\/wp-content\/uploads\/2025\/01\/2024121812012536676-300x200.jpg 300w, https:\/\/asofinbolivia.com\/wp-content\/uploads\/2025\/01\/2024121812012536676.jpg 837w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27cec62 elementor-widget elementor-widget-elementskit-social-share\" data-id=\"27cec62\" data-element_type=\"widget\" data-widget_type=\"elementskit-social-share.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<ul class=\"ekit_socialshare\">\n                            <li class=\"elementor-repeater-item-39ac008\" data-social=\"facebook\">\n                    <div class=\"facebook\">\n                                                                                                <i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>                                            <\/div>\n                <\/li>\n                                            <li class=\"elementor-repeater-item-44a930b\" data-social=\"twitter\">\n                    <div class=\"twitter\">\n                                                                                                <i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>                                            <\/div>\n                <\/li>\n                                            <li class=\"elementor-repeater-item-9a797fc\" data-social=\"line\">\n                    <div class=\"line\">\n                                                                                                <i aria-hidden=\"true\" class=\"icon icon-instagram-1\"><\/i>                                            <\/div>\n                <\/li>\n                                    <\/ul>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b014951 elementor-widget elementor-widget-text-editor\" data-id=\"b014951\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En los \u00faltimos a\u00f1os, Banco Ecofuturo ha invertido en la mejora y eficiencia de sus servicios digitales, esto debido a la demanda constante de la poblaci\u00f3n por el uso de servicios digitales f\u00e1ciles y seguros. Un dato interesante por parte de la entidad es que a septiembre del 2024 la actividad digital fue de 230.454 transacciones electr\u00f3nicas en la banca digital, un incremento del 100% en comparaci\u00f3n a similar fecha del a\u00f1o pasado, 115.411 transacciones.<\/p>\n<p>Cabe destacar que se experiment\u00f3 un avance acelerado en transacciones digitales. Ecofuturo realiz\u00f3 un total de 3.097.521 transacciones en 2023, de las cuales se llegaron a realizar 1.122.392 por medios digitales, representando el 36,24%.<\/p>\n<p>El servicio de banca digital es fundamental para los clientes de Ecofuturo, tal como afirma Alejandro Bustillos gerente general de la entidad, se ofertan m\u00faltiples beneficios que optimizan la experiencia bancaria y facilitan la gesti\u00f3n de sus finanzas. \u201cPor ejemplo, de un total de 250.304 clientes con cuentas de captaciones a septiembre de 2023, 32.318 (12,91%) ya utilizaban la banca digital\u201d, destac\u00f3 el ejecutivo.<\/p>\n<p>Un a\u00f1o despu\u00e9s, en similar periodo, pero de este a\u00f1o, la cifra mencionada creci\u00f3 significativamente de un total de 259.844 clientes de captaciones, 46.877 (18,04%) utilizan banca digital. \u201cEste incremento refleja el inter\u00e9s y preferencia por las soluciones digitales que Ecofuturo ofrece, en l\u00ednea con las necesidades y expectativas del sistema financiero nacional\u201d, explic\u00f3 Bustillos.<\/p>\n<p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05f3e0b elementor-widget elementor-widget-image\" data-id=\"05f3e0b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"199\" height=\"300\" src=\"https:\/\/asofinbolivia.com\/wp-content\/uploads\/2025\/01\/2024121812012624712-199x300.jpg\" class=\"attachment-medium size-medium wp-image-24134\" alt=\"\" srcset=\"https:\/\/asofinbolivia.com\/wp-content\/uploads\/2025\/01\/2024121812012624712-199x300.jpg 199w, https:\/\/asofinbolivia.com\/wp-content\/uploads\/2025\/01\/2024121812012624712-678x1024.jpg 678w, https:\/\/asofinbolivia.com\/wp-content\/uploads\/2025\/01\/2024121812012624712-768x1160.jpg 768w, https:\/\/asofinbolivia.com\/wp-content\/uploads\/2025\/01\/2024121812012624712.jpg 900w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-beaf3b7 elementor-widget elementor-widget-text-editor\" data-id=\"beaf3b7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>De las 230.454 transacciones realizadas en septiembre de 2024, las m\u00e1s utilizadas son:<\/p>\n<ul>\n<li>QR Interbancaria con el 74.87%<\/li>\n<li>Transferencias Interbancarias con el 10.54%<\/li>\n<li>QR a terceros en el mismo banco el 3,81%<\/li>\n<li>Transferencias a terceros en el mismo banco con el 2,97%<\/li>\n<li>Pago servicio ENTEL con el 2,68%<\/li>\n<li>Transferencias a cuentas propias en el mismo banco con el 1,98%<\/li>\n<\/ul>\n<p><br \/><span style=\"color: #993300;\"><strong>Defensa ante ciberataques<\/strong><\/span><br \/>Algunos estudios de la banca destacan que los ciberataques han crecido tanto en volumen como en sofisticaci\u00f3n, impulsados por el aumento del uso de servicios digitales y el crecimiento del trabajo remoto.<\/p>\n<p>De acuerdo con Rehizner K\u00f6ther, experto en ciberseguridad y director de Kerberos Latam, el estado actual de la ciberseguridad en la banca digital est\u00e1 mucho mejor que hace algunos a\u00f1os, ya que a escala latinoamericana, m\u00e1s del 90% de las entidades bancarias tienen implementadas soluciones de detecci\u00f3n y an\u00e1lisis de eventos de seguridad, adem\u00e1s de est\u00e1ndares como ISO 27001.<\/p>\n<p>Sin embargo, s\u00f3lo el 51% utilizan tecnolog\u00edas emergentes como Big Data, Machine Learning o Artificial Intelligence para detectar y prevenir amenazas o patrones asociados a fraudes, seg\u00fan datos de la Organizaci\u00f3n de los Estados Americanos (OEA). En el caso Bolivia, K\u00f6ther ha visto gran actividad del troyano bancario Mispadu, el cual secuestra credenciales de los principales bancos del pa\u00eds desde el computador del cliente.<\/p>\n<p>\u201cEn cuanto a innovaciones y desaf\u00edos, la adopci\u00f3n de las tecnolog\u00edas emergentes previamente mencionadas sirve para poder estar a la altura de las amenazas actuales, las cuales ya est\u00e1n siendo utilizadas por ataques y m\u00e1s aun con la amenaza cu\u00e1ntica que se pronostica para dentro de los pr\u00f3ximos 10 a\u00f1os\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Al respecto, el Banco Ecofuturo afirma que se han intensificado las medidas de seguridad, implementando tecnolog\u00edas avanzadas con el objetivo de proteger de manera proactiva los activos financieros e informaci\u00f3n personal de sus clientes, adem\u00e1s de incluir actividades de educaci\u00f3n sobre las mejores pr\u00e1cticas para los usuarios con el fin de mantener un entorno digital seguro.<\/p>\n<p>\u201cEn Ecofuturo la seguridad de las transacciones digitales y la protecci\u00f3n de la informaci\u00f3n de sus clientes es una prioridad absoluta. Se implement\u00f3 una combinaci\u00f3n de tecnolog\u00edas avanzadas y mejores pr\u00e1cticas que incluyen la encriptaci\u00f3n desde el origen de la transacci\u00f3n hasta el destino, adem\u00e1s de un Firewall, un WAF, un IPS, un EDR, y plantillas de aseguramiento las cuales protegen la infraestructura tecnol\u00f3gica\u201d, explic\u00f3 Bustillos.<\/p>\n<p>La entidad cuenta con un Firewall de \u00faltima generaci\u00f3n, un WAF el cual bloquea diferentes tipos de ataques, un IPS el cual monitorea el tr\u00e1fico de red y un antivirus el cual realiza escaneos peri\u00f3dicos. \u201cCon estas medidas, aseguramos un entorno confiable y seguro para todas las operaciones digitales\u201d, destac\u00f3 el Gerente General de Banco Ecofuturo.<\/p>\n<p>Para la entidad financiera, la gesti\u00f3n de las amenazas de ciberseguridad es un proceso clave para garantizar la protecci\u00f3n de la informaci\u00f3n y las transacciones de los clientes. Cuenta con un enfoque integral que combina tecnolog\u00edas avanzadas, protocolos estrictos y un equipo especializado en ciberseguridad.<\/p>\n<p>Se realiza constantes evaluaciones para identificar las diferentes amenazas que pueden vulnerar los controles y los sistemas asociados a las plataformas digitales, una vez que se identifica esta amenaza se procede a subsanar y mejorar los controles de forma preventiva, velando la informaci\u00f3n de los clientes y sus transacciones.<\/p>\n<p>Sin embargo, no se debe pasar por alto la educaci\u00f3n del consumidor como un paso clave en la prevenci\u00f3n de fraudes en banca digital. Ecofuturo considera que la protecci\u00f3n de las cuentas y la informaci\u00f3n de sus clientes no depende \u00fanicamente de las medidas de seguridad que implementa, tambi\u00e9n del conocimiento y las pr\u00e1cticas seguras que adoptan los propios usuarios para evitar los diferentes fraudes,<\/p>\n<p>En este sentido, brindan constantes capacitaciones y educaci\u00f3n financiera, los cuales informan de manera peri\u00f3dica los nuevos fraudes que puede haber en la banca digital como el phishing, a trav\u00e9s de llamadas o mensajes y el robo de identidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bb53e79 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bb53e79\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7865e78\" data-id=\"7865e78\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3964c7f elementor-widget elementor-widget-heading\" data-id=\"3964c7f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Fuente:<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6e65c05\" data-id=\"6e65c05\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06507ea elementor-widget elementor-widget-heading\" data-id=\"06507ea\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.economy.com.bo\/articulo\/banca-finanzas\/ecofuturo-experimento-crecimiento-servicios-digitales-enfocados-seguridad-usuario\/20241218120421016402.html\" target=\"_blank\">Economy<\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-542fe4a0 elementor-widget elementor-widget-heading\" data-id=\"542fe4a0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.economy.com.bo\/articulo\/banca-finanzas\/ecofuturo-experimento-crecimiento-servicios-digitales-enfocados-seguridad-usuario\/20241218120421016402.html\">Publicado el 18\/12\/2024<\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-49323b9\" data-id=\"49323b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p><b>Fecha:<\/b> 18 de diciembte de 2024<\/p>\n<p>\n<span class=\"cards--two__rect\"><\/span><br \/>\n<span class=\"cards--two__tri\"><\/span><\/p>\n","protected":false},"author":7,"featured_media":24129,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[51,50,49],"class_list":["post-24128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-finanzas","tag-inclusion","tag-lif"],"_links":{"self":[{"href":"https:\/\/asofinbolivia.com\/index.php\/wp-json\/wp\/v2\/posts\/24128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asofinbolivia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asofinbolivia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asofinbolivia.com\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/asofinbolivia.com\/index.php\/wp-json\/wp\/v2\/comments?post=24128"}],"version-history":[{"count":8,"href":"https:\/\/asofinbolivia.com\/index.php\/wp-json\/wp\/v2\/posts\/24128\/revisions"}],"predecessor-version":[{"id":24140,"href":"https:\/\/asofinbolivia.com\/index.php\/wp-json\/wp\/v2\/posts\/24128\/revisions\/24140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asofinbolivia.com\/index.php\/wp-json\/wp\/v2\/media\/24129"}],"wp:attachment":[{"href":"https:\/\/asofinbolivia.com\/index.php\/wp-json\/wp\/v2\/media?parent=24128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asofinbolivia.com\/index.php\/wp-json\/wp\/v2\/categories?post=24128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asofinbolivia.com\/index.php\/wp-json\/wp\/v2\/tags?post=24128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}